{"id":3339,"date":"2017-12-07T17:08:25","date_gmt":"2017-12-07T17:08:25","guid":{"rendered":"https:\/\/eagtrans.com\/?page_id=3339"},"modified":"2018-02-17T11:12:41","modified_gmt":"2018-02-17T10:12:41","slug":"portefeuille","status":"publish","type":"page","link":"https:\/\/eagtrans.com\/es\/portfolio\/","title":{"rendered":"Portfolio"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;3306&#8243; bg_position=&#8221;left top&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; top_padding=&#8221;12%&#8221; bottom_padding=&#8221;12%&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;flip-in&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h1><\/h1>\n<h1 style=\"text-align: left;\">PORTFOLIO<\/h1>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1514382913198{padding-bottom: 30px !important;}&#8221;]\n<h2><span style=\"font-weight: 400;\">Desde el principio, he tenido la oportunidad de trabajar para distintos clientes en proyectos variados que me han ido ayudando a configurar mis \u00e1reas de especializaci\u00f3n.<\/span><\/h2>\n<h2 style=\"text-align: center;\"><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1514382940632{padding-bottom: 30px !important;}&#8221;]\n<h2><span style=\"font-weight: 400;\">Si desea solicitar una muestra de algunas muestras de trabajo tanto de traducci\u00f3n como de correcci\u00f3n para poder evaluar la calidad y el estilo, por favor, cumplimente el campo de abajo para facilitarme su correo electr\u00f3nico y recibir los archivos con la mayor brevedad posible. Tambi\u00e9n puede solicitar dichas muestras a trav\u00e9s de un correo electr\u00f3nico a <\/span><strong><a href=\"mailto:traduccion@eagtrans.com?subject=Saludos%20desde%20su%20web&amp;body=\">traduccion@eagtrans.com<\/a>.<\/strong><\/h2>\n<h2 style=\"text-align: center;\"><\/h2>\n[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;clouds&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;5px&#8221; width=&#8221;1\/2&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;8px&#8221; column_border_color=&#8221;#ffffff&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3351-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"3351\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/3339#wpcf7-f3351-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3351\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3351-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Correo electr\u00f3nico (requerido)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"210\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/2&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;3529&#8243; alignment=&#8221;center&#8221; animation=&#8221;Fade In From Right&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; enable_gradient=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;curve&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column][\/vc_row]","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; bg_image=&#8221;3306&#8243; bg_position=&#8221;left top&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; top_padding=&#8221;12%&#8221; bottom_padding=&#8221;12%&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; shape_type=&#8221;&#8221;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;flip-in&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text] PORTFOLIO [\/vc_column_text][\/vc_column][\/vc_row][vc_row&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-3339","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Portfolio | Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora<\/title>\n<meta name=\"description\" content=\"Con mi portfolio quiero que tenga la posiblidad de solicitar una muestra de algunas muestras de trabajo tanto de traducci\u00f3n como de correcci\u00f3n para poder...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eagtrans.com\/es\/portfolio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portfolio | Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora\" \/>\n<meta property=\"og:description\" content=\"Con mi portfolio quiero que tenga la posiblidad de solicitar una muestra de algunas muestras de trabajo tanto de traducci\u00f3n como de correcci\u00f3n para poder...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eagtrans.com\/es\/portfolio\/\" \/>\n<meta property=\"og:site_name\" content=\"Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-17T10:12:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eagtrans.com\/es\/portfolio\/\",\"url\":\"https:\/\/eagtrans.com\/es\/portfolio\/\",\"name\":\"Portfolio | Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora\",\"isPartOf\":{\"@id\":\"https:\/\/eagtrans.com\/es\/#website\"},\"datePublished\":\"2017-12-07T17:08:25+00:00\",\"dateModified\":\"2018-02-17T10:12:41+00:00\",\"description\":\"Con mi portfolio quiero que tenga la posiblidad de solicitar una muestra de algunas muestras de trabajo tanto de traducci\u00f3n como de correcci\u00f3n para poder...\",\"breadcrumb\":{\"@id\":\"https:\/\/eagtrans.com\/es\/portfolio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eagtrans.com\/es\/portfolio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eagtrans.com\/es\/portfolio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/eagtrans.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eagtrans.com\/es\/#website\",\"url\":\"https:\/\/eagtrans.com\/es\/\",\"name\":\"Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora\",\"description\":\"Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eagtrans.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portfolio | Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora","description":"Con mi portfolio quiero que tenga la posiblidad de solicitar una muestra de algunas muestras de trabajo tanto de traducci\u00f3n como de correcci\u00f3n para poder...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eagtrans.com\/es\/portfolio\/","og_locale":"es_ES","og_type":"article","og_title":"Portfolio | Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora","og_description":"Con mi portfolio quiero que tenga la posiblidad de solicitar una muestra de algunas muestras de trabajo tanto de traducci\u00f3n como de correcci\u00f3n para poder...","og_url":"https:\/\/eagtrans.com\/es\/portfolio\/","og_site_name":"Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora","article_modified_time":"2018-02-17T10:12:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eagtrans.com\/es\/portfolio\/","url":"https:\/\/eagtrans.com\/es\/portfolio\/","name":"Portfolio | Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora","isPartOf":{"@id":"https:\/\/eagtrans.com\/es\/#website"},"datePublished":"2017-12-07T17:08:25+00:00","dateModified":"2018-02-17T10:12:41+00:00","description":"Con mi portfolio quiero que tenga la posiblidad de solicitar una muestra de algunas muestras de trabajo tanto de traducci\u00f3n como de correcci\u00f3n para poder...","breadcrumb":{"@id":"https:\/\/eagtrans.com\/es\/portfolio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eagtrans.com\/es\/portfolio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eagtrans.com\/es\/portfolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/eagtrans.com\/es\/"},{"@type":"ListItem","position":2,"name":"Portfolio"}]},{"@type":"WebSite","@id":"https:\/\/eagtrans.com\/es\/#website","url":"https:\/\/eagtrans.com\/es\/","name":"Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora","description":"Elvira Aguilar Gonz\u00e1lez - eagtrans.com | Traductora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eagtrans.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PaNv5I-RR","_links":{"self":[{"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/pages\/3339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/comments?post=3339"}],"version-history":[{"count":45,"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/pages\/3339\/revisions"}],"predecessor-version":[{"id":3785,"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/pages\/3339\/revisions\/3785"}],"wp:attachment":[{"href":"https:\/\/eagtrans.com\/es\/wp-json\/wp\/v2\/media?parent=3339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}